{"id":13,"date":"2023-05-26T13:20:18","date_gmt":"2023-05-26T11:20:18","guid":{"rendered":"https:\/\/comprensivogrottammare.istruzioneweb.it\/index.php\/la-scuola\/presentazione\/"},"modified":"2024-06-14T09:49:16","modified_gmt":"2024-06-14T07:49:16","slug":"presentazione","status":"publish","type":"page","link":"https:\/\/comprensivogrottammare.edu.it\/index.php\/la-scuola\/presentazione\/","title":{"rendered":"Presentazione"},"content":{"rendered":"<p>Il nostro I.C. \u00e8 l&#8217;unico del comune di Grottammare. Il territorio si articola in due nuclei urbani, il centro abitato si estende lungo la costa fino alle pendici delle vicine colline dove spicca l&#8217;antico borgo medievale.<\/p>\n<p>L\u2019UNICIT\u00c0 DELL\u2019ALUNNO \u00e8 la missione dell&#8217;istituto e le priorit\u00e0 sono definite chiaramente, discusse all\u2019inizio di ogni anno scolastico, condivise all&#8217;interno della comunit\u00e0 scolastica, deliberate dagli organi collegiali e rese note anche all&#8217;esterno (famiglie e territorio) attraverso il Piano Triennale dell&#8217;Offerta Formativa pubblicato all&#8217;albo on line.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nostro I.C. \u00e8 l&#8217;unico del comune di Grottammare. Il territorio si articola in due nuclei urbani, il centro abitato si estende lungo la costa fino alle pendici delle vicine colline dove spicca l&#8217;antico borgo medievale. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/presentazione.php","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/pages\/6"}],"wp:attachment":[{"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/media?parent=13"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprensivogrottammare.edu.it\/index.php\/wp-json\/wp\/v2\/tags?post=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}